{"id":7113,"date":"2026-05-31T15:03:02","date_gmt":"2026-05-31T16:03:02","guid":{"rendered":"https:\/\/www.point-editions.com\/?p=7113"},"modified":"2026-05-31T15:35:47","modified_gmt":"2026-05-31T16:35:47","slug":"830-to-the-dead-poet-of-obscurity","status":"publish","type":"post","link":"https:\/\/www.point-editions.com\/fr\/830-to-the-dead-poet-of-obscurity\/","title":{"rendered":"830 | TO THE DEAD POET OF OBSCURITY"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7114 aligncenter\" src=\"https:\/\/www.point-editions.com\/wp-content\/uploads\/2026\/05\/ecrire.jpg\" alt=\"\" width=\"183\" height=\"275\" \/><\/p>\n<p style=\"text-align: center;\"><strong>Au po\u00e8te d\u00e9c\u00e9d\u00e9, oubli\u00e9<\/strong><\/p>\n<p style=\"text-align: center;\"><em>(en l\u2019honneur du po\u00e8te d\u00e9c\u00e9d\u00e9, non publi\u00e9)<\/em><\/p>\n<p style=\"text-align: center;\">Bien jou\u00e9\u00a0!<br \/>\nVous avez gagn\u00e9\u00a0!<br \/>\nVous ne devez avoir aucun regret,<br \/>\nvos po\u00e8mes non publi\u00e9s<br \/>\n&#8211; ne l\u2019oubliez jamais &#8211;<br \/>\nne sont pas enterr\u00e9s<br \/>\nne sont pas courb\u00e9s<br \/>\nsous la puissance du temps.<br \/>\nComme l\u2019or<br \/>\nils demeurent<br \/>\ndans la terre.<br \/>\nIls restent,<br \/>\nne fondent jamais,<br \/>\nils viennent peut-\u00eatre tard,<br \/>\nmais un jour<br \/>\nils seront pr\u00e9sent\u00e9s<br \/>\n\u00e0 leur population<br \/>\npour offrir leur douce<br \/>\n\u00e9ternelle essence.<\/p>\n<p style=\"text-align: center;\"><strong>Dimitris P. Kraniotis<\/strong><strong>, <\/strong>Gr\u00e8ce<\/p>\n<p style=\"text-align: center;\"><strong><em>Traduction de Lemonia Mourka, Germain Droogenbroodt et Elisabeth Gerlache<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Au po\u00e8te d\u00e9c\u00e9d\u00e9, oubli\u00e9 (en l\u2019honneur du po\u00e8te d\u00e9c\u00e9d\u00e9, non publi\u00e9) Bien jou\u00e9\u00a0! Vous avez gagn\u00e9\u00a0! Vous ne devez avoir aucun regret, vos po\u00e8mes non publi\u00e9s &#8211; ne l\u2019oubliez jamais &#8211; ne sont pas enterr\u00e9s ne sont pas courb\u00e9s sous la puissance du temps. Comme l\u2019or ils demeurent dans la terre. Ils restent, ne fondent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[14],"tags":[],"class_list":["post-7113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poemas"],"_links":{"self":[{"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/posts\/7113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/comments?post=7113"}],"version-history":[{"count":3,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/posts\/7113\/revisions"}],"predecessor-version":[{"id":7123,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/posts\/7113\/revisions\/7123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/media\/7114"}],"wp:attachment":[{"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/media?parent=7113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/categories?post=7113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.point-editions.com\/fr\/wp-json\/wp\/v2\/tags?post=7113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}